{"id":289,"date":"2021-03-18T11:51:59","date_gmt":"2021-03-18T10:51:59","guid":{"rendered":"http:\/\/gekatec.de.domainpreview.eu\/?page_id=289"},"modified":"2025-02-12T13:44:02","modified_gmt":"2025-02-12T12:44:02","slug":"impressum","status":"publish","type":"page","link":"https:\/\/www.gekatec.de\/en\/impressum\/","title":{"rendered":"LEGAL NOTICE"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; admin_label=&#8220;Header Section&#8220; module_id=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;RGBA(0,0,0,0)&#8220; custom_padding=&#8220;|||&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_fullwidth_header title=&#8220;Impressum&#8220; text_orientation=&#8220;center&#8220; background_overlay_color=&#8220;rgba(0,0,0,0.5)&#8220; content_max_width_last_edited=&#8220;off|desktop&#8220; admin_label=&#8220;Contents&#8220; _builder_version=&#8220;4.16&#8243; title_font=&#8220;Oswald|||on|&#8220; title_text_align=&#8220;center&#8220; title_font_size=&#8220;62px&#8220; title_letter_spacing=&#8220;0.05em&#8220; title_line_height=&#8220;1.5em&#8220; content_font=&#8220;Oswald|200|||||||&#8220; content_font_size=&#8220;35px&#8220; subhead_font=&#8220;Oswald||||||||&#8220; subhead_font_size=&#8220;35px&#8220; subhead_line_height=&#8220;2em&#8220; background_color=&#8220;rgba(255, 255, 255, 0)&#8220; background_image=&#8220;https:\/\/www.gekatec.de\/inhalde\/uploads\/2021\/03\/AdobeStock_125734172_Preview.jpeg&#8220; custom_button_one=&#8220;on&#8220; button_one_text_size=&#8220;15px&#8220; button_one_bg_color=&#8220;#dca57d&#8220; button_one_border_width=&#8220;10px&#8220; button_one_border_color=&#8220;#dca57d&#8220; button_one_border_radius=&#8220;0px&#8220; button_one_letter_spacing=&#8220;3px&#8220; button_one_font=&#8220;Oswald|||on|&#8220; button_one_use_icon=&#8220;off&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;5%||5%|&#8220; animation_style=&#8220;fade&#8220; animation_starting_opacity=&#8220;50%&#8220; animation_speed_curve=&#8220;ease-in&#8220; title_font_size_tablet=&#8220;60px&#8220; title_font_size_phone=&#8220;40px&#8220; title_font_size_last_edited=&#8220;on|phone&#8220; button_one_border_color_hover=&#8220;#c99872&#8243; button_one_border_radius_hover=&#8220;0px&#8220; button_one_letter_spacing_hover=&#8220;3px&#8220; button_one_bg_color_hover=&#8220;#c99872&#8243; global_colors_info=&#8220;{}&#8220; button_one_text_size__hover_enabled=&#8220;off&#8220; button_two_text_size__hover_enabled=&#8220;off&#8220; button_one_text_color__hover_enabled=&#8220;off&#8220; button_two_text_color__hover_enabled=&#8220;off&#8220; button_one_border_width__hover_enabled=&#8220;off&#8220; button_two_border_width__hover_enabled=&#8220;off&#8220; button_one_border_color__hover_enabled=&#8220;on&#8220; button_one_border_color__hover=&#8220;#c99872&#8243; button_two_border_color__hover_enabled=&#8220;off&#8220; button_one_border_radius__hover_enabled=&#8220;on&#8220; button_one_border_radius__hover=&#8220;0px&#8220; button_two_border_radius__hover_enabled=&#8220;off&#8220; button_one_letter_spacing__hover_enabled=&#8220;on&#8220; button_one_letter_spacing__hover=&#8220;3px&#8220; button_two_letter_spacing__hover_enabled=&#8220;off&#8220; button_one_bg_color__hover_enabled=&#8220;on&#8220; button_one_bg_color__hover=&#8220;#c99872&#8243; button_two_bg_color__hover_enabled=&#8220;off&#8220;][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Features&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;100px|0px|100px|0px&#8220; bottom_divider_color=&#8220;RGBA(0,0,0,0)&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row admin_label=&#8220;Section Header&#8220; _builder_version=&#8220;4.16&#8243; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|||&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text disabled_on=&#8220;off|off|off&#8220; admin_label=&#8220;Subtittle&#8220; _builder_version=&#8220;4.27.4&#8243; text_font=&#8220;Nunito||||||||&#8220; text_text_color=&#8220;#787070&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; header_font=&#8220;Oswald||||&#8220; header_font_size=&#8220;16px&#8220; header_letter_spacing=&#8220;2px&#8220; header_line_height=&#8220;1.7em&#8220; header_2_font=&#8220;Oswald||||||||&#8220; text_orientation=&#8220;center&#8220; max_width_tablet=&#8220;&#8220; max_width_phone=&#8220;&#8220; max_width_last_edited=&#8220;on|phone&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;-30px||67px|||&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h2 style=\"text-align: left;\">https:\/\/www.medienhaus-erzgebirge.de\/Angaben gem\u00e4\u00df \u00a7 5 TMG<\/h2>\n<p style=\"text-align: left;\">GeKa-Tec GmbH\u00a0Anlagen- und Metalltechnik<br \/>Genshagener Stra\u00dfe 42a<br \/>14979 Gro\u00dfbeeren<\/p>\n<p style=\"text-align: left;\"><strong>Vertreten durch:<\/strong><br \/>Herr Thomas Gehrz<\/p>\n<h2 style=\"text-align: left;\">Kontakt<\/h2>\n<p style=\"text-align: left;\">Telefon: 033701 74246-0<br \/>Fax: 033701 74246-1<br \/>E-Mail:\u00a0<a href=\"https:\/\/www.medienhaus-erzgebirge.de\/\">&#x69;&#110;&#x66;&#111;&#64;&#x67;&#101;k&#x61;&#116;&#x65;&#x63;&#46;&#x64;&#101;<\/a><\/p>\n<h2 style=\"text-align: left;\">Umsatzsteuer-ID<\/h2>\n<p style=\"text-align: left;\">Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz:<br \/>DE812079093<\/p>\n<h2 style=\"text-align: left;\">EU-Streitschlichtung<\/h2>\n<p style=\"text-align: left;\">Die Europ\u00e4ische Kommission stellt eine Plattform zur Online-Streitbeilegung (OS) bereit: <a href=\"https:\/\/www.medienhaus-erzgebirge.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/ec.europa.eu\/consumers\/odr<\/a>.<br \/>Unsere E-Mail-Adresse finden Sie oben im Impressum.<\/p>\n<h2 style=\"text-align: left;\">Verbraucher\u00adstreit\u00adbeilegung\/Universal\u00adschlichtungs\u00adstelle<\/h2>\n<p style=\"text-align: left;\">Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen.<\/p>\n<h3 style=\"text-align: left;\">Haftung f\u00fcr Inhalte<\/h3>\n<p style=\"text-align: left;\">Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen.<\/p>\n<p style=\"text-align: left;\">Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen.<\/p>\n<h3 style=\"text-align: left;\">Haftung f\u00fcr Links<\/h3>\n<p style=\"text-align: left;\">Unser Angebot enth\u00e4lt Links zu externen Websites Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter oder Betreiber der Seiten verantwortlich. Die verlinkten Seiten wurden zum Zeitpunkt der Verlinkung auf m\u00f6gliche Rechtsverst\u00f6\u00dfe \u00fcberpr\u00fcft. Rechtswidrige Inhalte waren zum Zeitpunkt der Verlinkung nicht erkennbar.<\/p>\n<p style=\"text-align: left;\">Eine permanente inhaltliche Kontrolle der verlinkten Seiten ist jedoch ohne konkrete Anhaltspunkte einer Rechtsverletzung nicht zumutbar. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Links umgehend entfernen.<\/p>\n<h3 style=\"text-align: left;\">Urheberrecht<\/h3>\n<p style=\"text-align: left;\">Die durch die Seitenbetreiber erstellten Inhalte und Werke auf diesen Seiten unterliegen dem deutschen Urheberrecht. Die Vervielf\u00e4ltigung, Bearbeitung, Verbreitung und jede Art der Verwertung au\u00dferhalb der Grenzen des Urheberrechtes bed\u00fcrfen der schriftlichen Zustimmung des jeweiligen Autors bzw. Erstellers. Downloads und Kopien dieser Seite sind nur f\u00fcr den privaten, nicht kommerziellen Gebrauch gestattet.<\/p>\n<p style=\"text-align: left;\">Soweit die Inhalte auf dieser Seite nicht vom Betreiber erstellt wurden, werden die Urheberrechte Dritter beachtet. Insbesondere werden Inhalte Dritter als solche gekennzeichnet. Sollten Sie trotzdem auf eine Urheberrechtsverletzung aufmerksam werden, bitten wir um einen entsprechenden Hinweis. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Inhalte umgehend entfernen.<\/p>\n<h2 style=\"text-align: left;\">Webentwicklung<\/h2>\n<p style=\"text-align: left;\">Medienhaus Erzgebirge<br \/>Albin-Trommler-Stra\u00dfe 20<br \/>08297 Zw\u00f6nitz<br \/><a href=\"https:\/\/www.medienhaus-erzgebirge.de\/\" target=\"_blank\" rel=\"noopener\">www.medienhaus-erzgebirge.de<\/a><\/p>\n<h2 style=\"text-align: left;\"><span><\/span><\/h2>\n<h2 style=\"text-align: left;\"><span>IT Service<\/span><\/h2>\n<p style=\"text-align: left;\"><span>030-IT GmbH<br \/>Berliner Stra\u00dfe 26B<br \/>13507 Berlin<\/span><br \/><a href=\"https:\/\/www.medienhaus-erzgebirge.de\/\" class=\"\" contenteditable=\"false\" title=\"https:\/\/www.030-it.de\/\">https:\/\/www.030-it.de\/<\/a><\/p>\n<p style=\"text-align: left;\">Quelle: <a href=\"https:\/\/www.medienhaus-erzgebirge.de\/\">eRecht24<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.medienhaus-erzgebirge.de\/Angaben gem\u00e4\u00df \u00a7 5 TMG GeKa-Tec GmbH\u00a0Anlagen- und MetalltechnikGenshagener Stra\u00dfe 42a14979 Gro\u00dfbeeren Vertreten durch:Herr Thomas Gehrz Kontakt Telefon: 033701 74246-0Fax: 033701 74246-1E-Mail:\u00a0&#105;&#110;f&#x6f;&#x40;&#x67;&#101;&#107;a&#x74;&#x65;&#x63;&#46;&#100;e Umsatzsteuer-ID Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz:DE812079093 EU-Streitschlichtung Die Europ\u00e4ische Kommission stellt eine Plattform zur Online-Streitbeilegung (OS) bereit: https:\/\/ec.europa.eu\/consumers\/odr.Unsere E-Mail-Adresse finden Sie oben im Impressum. Verbraucher\u00adstreit\u00adbeilegung\/Universal\u00adschlichtungs\u00adstelle Wir sind nicht bereit oder verpflichtet, an [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-289","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.gekatec.de\/en\/wp-json\/wp\/v2\/pages\/289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gekatec.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gekatec.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gekatec.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gekatec.de\/en\/wp-json\/wp\/v2\/comments?post=289"}],"version-history":[{"count":7,"href":"https:\/\/www.gekatec.de\/en\/wp-json\/wp\/v2\/pages\/289\/revisions"}],"predecessor-version":[{"id":903,"href":"https:\/\/www.gekatec.de\/en\/wp-json\/wp\/v2\/pages\/289\/revisions\/903"}],"wp:attachment":[{"href":"https:\/\/www.gekatec.de\/en\/wp-json\/wp\/v2\/media?parent=289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}